{"id":867,"date":"2015-05-01T00:00:34","date_gmt":"2015-05-01T03:00:34","guid":{"rendered":"http:\/\/localhost\/siteby2019\/2015\/05\/01\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/"},"modified":"2023-11-08T12:32:08","modified_gmt":"2023-11-08T15:32:08","slug":"elgin-como-encontrar-o-seu-publico-nas-midias-sociais","status":"publish","type":"post","link":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/","title":{"rendered":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-586 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430954885-ec964fef79317e42dd000f8a0873738a.jpg\" alt=\"\" width=\"800\" height=\"236\" \/><\/p>\n<h2><b>O Planejamento<\/b><\/h2>\n<p>Para come\u00e7ar, agrupamos os produtos de acordo com sua funcionalidade e apelos que poderiam vir em torno dele. Organizamos o conte\u00fado para cada grupo de produtos e estudamos os poss\u00edveis clusters de interesse que consumiriam esse conte\u00fado. Depois disso, segmentamos a entrega de cada post atrav\u00e9s da ferramenta nativa do Facebook para garantirmos a otimiza\u00e7\u00e3o do alcance qualificado e, consequentemente, a otimiza\u00e7\u00e3o do budget. Yes Bitch!<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-587 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430952291-6008e8c116871bb2be5bb86975f45d14.png\" alt=\"\" width=\"600\" height=\"1680\" \/><\/p>\n<p>Os conte\u00fados criados v\u00e3o al\u00e9m de apresentar o produto. Com criatividade, n\u00f3s os inserimos de forma s\u00fatil em nossas postagens, utilizando temas variados, sejam dicas cotidianas, decora\u00e7\u00e3o ou at\u00e9 mesmo utilizando um quiz como incentivo a intera\u00e7\u00e3o. Sempre contextualizados com a sazonalidade aproveitando assuntos do momento, criando conte\u00fados realmente relevantes sobre o universo do produto.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-588 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430956158-861ffc03d727236212576815a7627e9f.jpg\" alt=\"\" width=\"800\" height=\"236\" \/><\/p>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1564558107151470:0\" data-width=\"500\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1564558107151470:0\"><p>Voc\u00ea consegue colocar na sequ\u00eancia a frase abaixo do escritor Jo\u00e3o Bosco da Silva? #Cotidiano #Fragmentadora #Elgin Posted by\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\">Grupo Elgin<\/a>\u00a0on\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1564558107151470:0\">Tuesday, 14 April 2015<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1549524231988191:0\" data-width=\"500\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1549524231988191:0\"><p>Hoje \u00e9 o Dia do Telefone e nada melhor para comemorar que visitar o shopping Elgin para escolher o telefone que mais se\u2026 Posted by\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\">Grupo Elgin<\/a>\u00a0on\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1549524231988191:0\">Tuesday, 10 March 2015<\/a><\/p><\/blockquote>\n<blockquote cite=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1549524231988191:0\"><p>Durante os meses, acompanhamos o progresso do envolvimento dos f\u00e3s com as postagens e quais tipos f\u00e3s se destacavam na p\u00e1gina. Constatamos que algumas editorias de conte\u00fado se destacavam mais. Uma das que mais se destacaram foi o envolvimento dos artes\u00e3os (sim, eles ainda existem e usam muito o Facebook! Quem n\u00e3o usa?). VOIL\u00c1!<\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1546681375605810:0\" data-width=\"500\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1546681375605810:0\"><p>Venha conferir mais um passo a passo para voc\u00ea fazer um ba\u00fa de brinquedos! \u00c9 s\u00f3 clicar aqui: http:\/\/s87.eu\/BauParaBrinquedos #NoBlog #Elgin #Decora\u00e7\u00e3o #BauParaBrinquedos Posted by\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\">Grupo Elgin<\/a>\u00a0on\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\/posts\/1546681375605810:0\">Friday, 6 March 2015<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/GrupoElgin\/videos\/1521581668115781\/\" data-width=\"500\">\n<div class=\"fb-xfbml-parse-ignore\">\n<blockquote cite=\"https:\/\/www.facebook.com\/GrupoElgin\/videos\/1521581668115781\/\"><p>Voc\u00ea nunca sabe quando precisar\u00e1 de uma dessas, ent\u00e3o previna-se e compre a sua agora! http:\/\/s87.eu\/Luminaria_LED #Elgin #LuzDeEmerg\u00eancia #ProdutoElgin Posted by\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\">Grupo Elgin<\/a>\u00a0on\u00a0<a href=\"https:\/\/www.facebook.com\/GrupoElgin\/videos\/1521581668115781\/\">Saturday, 17 January 2015<\/a><\/p><\/blockquote>\n<h2>O Blog Elgin DIY<\/h2>\n<p>Assim surgiu o insight de produzirmos posts de DIY, inserindo as m\u00e1quinas de costura nas postagens e criarmos um blog com diversos passo-\u00e0-passo,\u00a0para que nosso target seguisse sozinho em casa, trazendo valor \u00e0 marca e melhorando a posi\u00e7\u00e3o na busca org\u00e2nica no Google.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-589 size-large\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430953007-f980aeaf68c2db8e933f71807a86f0de-1024x917.jpg\" alt=\"\" width=\"1024\" height=\"917\" \/><\/p>\n<p>A qualidade do conte\u00fado foi comprovada atrav\u00e9s dos dados no Analytics. \u00a0Tempo m\u00e9dio alt\u00edssimo, \u00a0e m\u00e9dia superior de 8.000 page views m\u00eas, em menos de 6 meses.A estrat\u00e9gia de SEO foi bem sucedida e a cada m\u00eas crescemos na quantidade de tr\u00e1fego vindo do Google.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-590 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430953965-197f2989e176a18e13dc41c91fb25d80.jpg\" alt=\"\" width=\"998\" height=\"544\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-591 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430953987-f8ff0b78045cdceedae7b324df71e84d.jpg\" alt=\"\" width=\"744\" height=\"503\" \/><\/p>\n<h2><\/h2>\n<h2>Aquisi\u00e7\u00e3o de F\u00e3s no Facebook<\/h2>\n<p>Enquanto todos reclamam do alto pre\u00e7o do Facebook, n\u00f3s comprovamos que ainda \u00e9 poss\u00edvel, sim, obtermos f\u00e3s de qualidade com custo bem baixo. E foi assim que conseguimos bater a meta de f\u00e3s estabelecida para 1 ano em 5 meses, mantendo o engajamento alto. Otimizamos nossas campanha de m\u00eddia sem perder qualidade do f\u00e3. Isso \u00e9 facilmente percebido ao analisar a taxa de engajamento dos posts. Vale ressaltar que\u00a0<strong>90% dos resultados s\u00e3o org\u00e2nicos<\/strong>, apenas 10% s\u00e3o fruto de alcance pago.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-592 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430954274-f16424a934d06edb2bee3a99d724887f.png\" alt=\"\" width=\"977\" height=\"737\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-593 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430954303-4075b0aa1e4bbc7e26fb75e89bff7309.png\" alt=\"\" width=\"977\" height=\"737\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-594 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1430955738-d8824cab2ef27e6061255983df96b591.jpg\" alt=\"\" width=\"800\" height=\"236\" \/><\/p>\n<\/div>\n<h2>As promo\u00e7\u00f5es\u00a0bombaram na p\u00e1gina da Elgin e superam nossas expectativas.<\/h2>\n<p>N\u00f3s tamb\u00e9m promovemos diversos concursos culturais ao longo desse per\u00edodo, tudo regulamentado pela Caixa, \u00e9 claro. Como exemplo, o\u00a0Concurso Ver\u00e3o Perfeito, que premiamos com um ar condicionado a melhor frase sobre o calor absurdo do ver\u00e3o passado, foi um sucesso. O concurso certo, na hora certa, com o pr\u00eamio certo: BINGO!\u00a0<strong>Foram mais de 4.000 mil cadastros!<\/strong>\u00a0O sucesso dos concursos segue, e estamos com uma promo\u00e7\u00e3o super legal para o Dia das M\u00e3es, que claro, est\u00e1 bombando! \ud83d\ude09<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-595 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/1431048195-60135bac605d5f4402b882bdfde67058.jpg\" alt=\"\" width=\"600\" height=\"1444\" \/><\/p>\n<p>Aqui \u00e9 correria! \u00c9 a vida real, com clientes reais, sem mega budgets ou premia\u00e7\u00f5es em Cannes, Apenas uma campanha redonda e bem otimizada, gerando resultados ao nosso cliente. E a\u00ed? Voc\u00ea ainda acha que n\u00e3o d\u00e1 para criar uma campanha criativa e com pouco investimento em m\u00eddia?\u00a0Melhor revisar seus conceitos, par\u00e7a! Vem pro nosso mundo!<\/p>\n<h3><em>Leia tamb\u00e9m: <a href=\"http:\/\/b-young.me\/campanha-nas-midias-sociais-acao-de-lancamento-1a-temporada-de-the-strain\/\">Campanha nas m\u00eddias sociais: A\u00e7\u00e3o de Lan\u00e7amento 1\u00aa Temporada de The Strain<\/a><\/em><\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Planejamento Para come\u00e7ar, agrupamos os produtos de acordo com sua funcionalidade e apelos que poderiam vir em torno dele. Organizamos o conte\u00fado para cada grupo de produtos e estudamos os poss\u00edveis clusters de interesse que consumiriam esse conte\u00fado. Depois disso, segmentamos a entrega de cada post atrav\u00e9s da ferramenta nativa do Facebook para garantirmos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[471,527],"tags":[668,616,644,669,620,479],"global-tags":[],"class_list":["post-867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-campanha-social-media","tag-campanha-de-midias-sociais","tag-case-de-midias-sociais","tag-conteudo","tag-elgin","tag-estrategia-em-midias-sociais","tag-midias-sociais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais - B-Young Social Media Co.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais\" \/>\n<meta property=\"og:description\" content=\"O Planejamento Para come\u00e7ar, agrupamos os produtos de acordo com sua funcionalidade e apelos que poderiam vir em torno dele. Organizamos o conte\u00fado para cada grupo de produtos e estudamos os poss\u00edveis clusters de interesse que consumiriam esse conte\u00fado. Depois disso, segmentamos a entrega de cada post atrav\u00e9s da ferramenta nativa do Facebook para garantirmos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/\" \/>\n<meta property=\"og:site_name\" content=\"B-Young Social Media Co.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agenciabyoung\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-01T03:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T15:32:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kaique C. Ribeiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaique C. Ribeiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/\"},\"author\":{\"name\":\"Kaique C. Ribeiro\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/person\\\/43d0dd6b09299911f71acce4257ac61d\"},\"headline\":\"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais\",\"datePublished\":\"2015-05-01T03:00:34+00:00\",\"dateModified\":\"2023-11-08T15:32:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/\"},\"wordCount\":698,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg\",\"keywords\":[\"campanha de midias sociais\",\"case de midias sociais\",\"conteudo\",\"elgin\",\"Estrat\u00e9gia em M\u00eddias Sociais\",\"midias sociais\"],\"articleSection\":[\"Artigos\",\"Campanha Social Media\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/\",\"name\":\"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais - B-Young Social Media Co.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg\",\"datePublished\":\"2015-05-01T03:00:34+00:00\",\"dateModified\":\"2023-11-08T15:32:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg\",\"contentUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg\",\"width\":1100,\"height\":985},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/b-young.me\\\/en\\\/agency-of-social-media\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/\",\"name\":\"B-Young Social Media Co.\",\"description\":\"Ag\u00eancia de M\u00eddias Sociais\",\"publisher\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/b-young.me\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\",\"name\":\"B-Young Social Media Co.\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_by.png\",\"contentUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_by.png\",\"width\":436,\"height\":131,\"caption\":\"B-Young Social Media Co.\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agenciabyoung\",\"https:\\\/\\\/www.instagram.com\\\/agencia_byoung\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/b-young\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCzBkLbvLBatSTJrPjENDuww\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/person\\\/43d0dd6b09299911f71acce4257ac61d\",\"name\":\"Kaique C. Ribeiro\",\"sameAs\":[\"https:\\\/\\\/karbro.com.br\"],\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/author\\\/kaique_dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais - B-Young Social Media Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/","og_locale":"en_US","og_type":"article","og_title":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais","og_description":"O Planejamento Para come\u00e7ar, agrupamos os produtos de acordo com sua funcionalidade e apelos que poderiam vir em torno dele. Organizamos o conte\u00fado para cada grupo de produtos e estudamos os poss\u00edveis clusters de interesse que consumiriam esse conte\u00fado. Depois disso, segmentamos a entrega de cada post atrav\u00e9s da ferramenta nativa do Facebook para garantirmos [&hellip;]","og_url":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/","og_site_name":"B-Young Social Media Co.","article_publisher":"https:\/\/www.facebook.com\/agenciabyoung","article_published_time":"2015-05-01T03:00:34+00:00","article_modified_time":"2023-11-08T15:32:08+00:00","og_image":[{"width":1100,"height":985,"url":"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg","type":"image\/jpeg"}],"author":"Kaique C. Ribeiro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kaique C. Ribeiro","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#article","isPartOf":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/"},"author":{"name":"Kaique C. Ribeiro","@id":"https:\/\/b-young.me\/en\/#\/schema\/person\/43d0dd6b09299911f71acce4257ac61d"},"headline":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais","datePublished":"2015-05-01T03:00:34+00:00","dateModified":"2023-11-08T15:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/"},"wordCount":698,"commentCount":0,"publisher":{"@id":"https:\/\/b-young.me\/en\/#organization"},"image":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg","keywords":["campanha de midias sociais","case de midias sociais","conteudo","elgin","Estrat\u00e9gia em M\u00eddias Sociais","midias sociais"],"articleSection":["Artigos","Campanha Social Media"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/","url":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/","name":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais - B-Young Social Media Co.","isPartOf":{"@id":"https:\/\/b-young.me\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#primaryimage"},"image":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg","datePublished":"2015-05-01T03:00:34+00:00","dateModified":"2023-11-08T15:32:08+00:00","breadcrumb":{"@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#primaryimage","url":"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg","contentUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2015\/05\/1430953007-f980aeaf68c2db8e933f71807a86f0de.jpg","width":1100,"height":985},{"@type":"BreadcrumbList","@id":"https:\/\/b-young.me\/en\/elgin-como-encontrar-o-seu-publico-nas-midias-sociais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/b-young.me\/en\/agency-of-social-media\/"},{"@type":"ListItem","position":2,"name":"Elgin: Como encontrar o seu p\u00fablico nas m\u00eddias sociais"}]},{"@type":"WebSite","@id":"https:\/\/b-young.me\/en\/#website","url":"https:\/\/b-young.me\/en\/","name":"B-Young Social Media Co.","description":"Ag\u00eancia de M\u00eddias Sociais","publisher":{"@id":"https:\/\/b-young.me\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/b-young.me\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/b-young.me\/en\/#organization","name":"B-Young Social Media Co.","url":"https:\/\/b-young.me\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/b-young.me\/en\/#\/schema\/logo\/image\/","url":"https:\/\/b-young.me\/wp-content\/uploads\/2022\/02\/logo_by.png","contentUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2022\/02\/logo_by.png","width":436,"height":131,"caption":"B-Young Social Media Co."},"image":{"@id":"https:\/\/b-young.me\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agenciabyoung","https:\/\/www.instagram.com\/agencia_byoung\/","https:\/\/www.linkedin.com\/company\/b-young\/","https:\/\/www.youtube.com\/channel\/UCzBkLbvLBatSTJrPjENDuww"]},{"@type":"Person","@id":"https:\/\/b-young.me\/en\/#\/schema\/person\/43d0dd6b09299911f71acce4257ac61d","name":"Kaique C. Ribeiro","sameAs":["https:\/\/karbro.com.br"],"url":"https:\/\/b-young.me\/en\/author\/kaique_dev\/"}]}},"_links":{"self":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts\/867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/comments?post=867"}],"version-history":[{"count":0,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts\/867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/media\/868"}],"wp:attachment":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/media?parent=867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/categories?post=867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/tags?post=867"},{"taxonomy":"global-tags","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/global-tags?post=867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}