{"id":807,"date":"2017-04-11T18:32:32","date_gmt":"2017-04-11T21:32:32","guid":{"rendered":"http:\/\/localhost\/siteby2019\/2017\/04\/11\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/"},"modified":"2023-11-28T11:38:29","modified_gmt":"2023-11-28T14:38:29","slug":"stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado","status":"publish","type":"post","link":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/","title":{"rendered":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado"},"content":{"rendered":"<p>Talvez voc\u00ea ainda n\u00e3o esteja 100% adaptado \u00e0\u00a0invas\u00e3o dos stories\u00a0nos seus apps preferidos, mas j\u00e1 \u00e9 hora de admitir, esta \u00e9 a realidade e n\u00e3o uma fase.<\/p>\n<p>O Facebook popularizou h\u00e1 10 anos o feed baseado em algor\u00edtimo. O Tinder popularizou o deslizar de sim\/n\u00e3o, junto ao consentimento bilateral nos aplicativos de encontro. O Blogger, os blogs. O Google, o Pagerank. O ICQ, as mensagens instant\u00e2neas.<\/p>\n<p>Os primeiros aplicativos que copiaram ou se basearam nestas funcionalidades foram chamados de clones. Para o Facebook, hoje, ser chamado de \u201cclone\u201d at\u00e9 ent\u00e3o n\u00e3o tem sido um problema, visto que deu um tiro de canh\u00e3o no \u201cStories\u201doutrora t\u00edmido a \u201cpequena\u201dcomunidade local do Snap.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-336 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/newsfeed1.png\" alt=\"\" width=\"524\" height=\"445\" \/><\/p>\n<p>No\u00a0<a href=\"https:\/\/old.b-young.me\/blog\" target=\"_blank\" rel=\"noopener noreferrer\"><em><strong>lan\u00e7amento<\/strong> <\/em><\/a>do Stories para o Instagram, o CEO Kevin Systrom fez a seguinte cita\u00e7\u00e3o:<\/p>\n<blockquote><p>\u201cIsto n\u00e3o \u00e9 mais sobre quem inventou o que. Isso \u00e9 sobre um formato, como voc\u00ea o traz para dentro de sua plataforma e o coloca para rodar.\u201d<\/p><\/blockquote>\n<p>Somente alguns meses depois, no lan\u00e7amento do Messenger Day, o VP de Messaging do Facebook refor\u00e7ou o sentimento de intimidade com a fun\u00e7\u00e3o:<\/p>\n<blockquote><p>\u201cCreio que o Stories \u00e9 definitivamente um formato, da mesma forma que o feed \u00e9 um formato.\u201d<\/p><\/blockquote>\n<p>\u00c9 consenso dentro da alta gest\u00e3o do Facebook que o <a href=\"https:\/\/old.b-young.me\/blog\" target=\"_blank\" rel=\"noopener noreferrer\"><em><strong>formato<\/strong> <\/em><\/a>de slideshow em foto\/video tornou-se um \u201cmust have\u201d, quest\u00e3o de evolu\u00e7\u00e3o, em todas as aplica\u00e7\u00f5es da companhia. Foi implementado no WhatsApp como vis\u00edvel forma de monetizar o canal at\u00e9 ent\u00e3o \u201cinexplorado\u201d, e est\u00e1 sendo testado para o Facebook.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-337 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/newsfeed2.jpg\" alt=\"\" width=\"680\" height=\"393\" \/><\/p>\n<h2>Do NewsFeed para o Stories, da c\u00e2mera digital para o Smartphone<\/h2>\n<p>Quando o Facebook lan\u00e7ou o NewsFeed em 2006, ele foi 100% projetado para desktops. Era perfeito para que voc\u00ea digitasse seus status em texto, diretamente do seu teclado bege, copiasse e colasse links de outros websites, pois afinal, voc\u00ea estava preso dentro da sua casa e n\u00e3o tinha nada muito legal para mostrar. Postar fotos ainda exigia o hom\u00e9rico esfor\u00e7o de baixar o conte\u00fado de sua c\u00e2mera digital, isso foi quase h\u00e1 um s\u00e9culo, bem antes de todos termos smartphones.<\/p>\n<p>Hoje, tanto o Facebook quanto o Snap est\u00e3o indo no caminho da comunica\u00e7\u00e3o visual, acompanhando a narrativa da vida de seus usu\u00e1rios. No dia do IPO do Snap, Evan Spiegel, CEO da plataforma, escreveu em carta aos investidores:<\/p>\n<blockquote><p>\u201cDa mesma maneira que o cursor do mouse foi o ponto de partida para produtos no desktop, a c\u00e2mera dos smartphones ser\u00e1 o ponto de partida para os produtos mobile.\u201d<\/p><\/blockquote>\n<p>Apenas uma semana depois, o gerente de produto do Messenger Day, Tony Leach disse:<\/p>\n<blockquote><p>\u201cGostamos de pensar na c\u00e2mera do seu smartphone como o novo teclado.\u201d<\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-338 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/newsfeed3.png\" alt=\"\" width=\"680\" height=\"405\" \/><\/p>\n<p>Isso quer dizer somente uma coisa \u2013 O newsfeed est\u00e1 ultrapassado, do ponto de vista de como os usu\u00e1rios criam conte\u00fado.<\/p>\n<p>A navega\u00e7\u00e3o vertical deixa gaps entre imagens e v\u00eddeos e nem sempre oferece uma experi\u00eancia totalmente imersiva na tela, pois n\u00e3o \u00e9 por natureza full screen.<\/p>\n<p>A intelig\u00eancia do algor\u00edtimo tamb\u00e9m j\u00e1 n\u00e3o atende 100% aos padr\u00f5es de cria\u00e7\u00e3o de conte\u00fado. H\u00e1 alguns anos, em que basicamente se postavam fotos e textos, e em que o consumo do conte\u00fado era espor\u00e1dico, a intelig\u00eancia do feed em juntar o que era recente com conte\u00fados postados h\u00e1 horas era necess\u00e1ria para que n\u00e3o perd\u00eassemos as hist\u00f3rias mais relevantes.<\/p>\n<p>Isso tamb\u00e9m se aplicava ao in\u00edcio do mobile, onde a capacidade tecnol\u00f3gica ainda limitava o que era poss\u00edvel ser ser compartilhado, digitalizando apenas os grandes highlights de nossas vidas.<\/p>\n<p>Por\u00e9m, com a evolu\u00e7\u00e3o do mobile, deixamos\u00a0para tr\u00e1s apenas os grandes momentos para trazer a narrativa completa de nossas vidas, de forma linear e cronol\u00f3gica. Onde, convenhamos, o NewsFeed n\u00e3o est\u00e1 preparado para ir. Mais do que apenas peda\u00e7os de um dia, hoje compartilhamos os passos e acontecimentos, o Stories, permite que ningu\u00e9m perca esta linha de acontecimentos que tem relev\u00e2ncia limitada \u00e0 certo per\u00edodo de tempo.<\/p>\n<p>Trazer o Stories para dentro das plataformas \u00e9 muito mais sobre adapta\u00e7\u00e3o e sobreviv\u00eancia do que sobre c\u00f3pia, mas principalmente sobre entender como o usu\u00e1rio gera conte\u00fado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-339 size-full\" src=\"https:\/\/old.b-young.me\/wp-content\/uploads\/2017\/07\/newsfeed4.png\" alt=\"\" width=\"680\" height=\"296\" \/><\/p>\n<p>Antes ser chamado de copi\u00e3o do que de ultrapassado.<\/p>\n<h3><em><strong>Confira tamb\u00e9m: <a href=\"http:\/\/b-young.me\/marcas-podem-utilizar-memes-em-sua-estrategia-nas-midias-sociais\/\">Marcas podem utilizar memes em sua estrat\u00e9gia nas m\u00eddias sociais?<\/a><\/strong><\/em><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Talvez voc\u00ea ainda n\u00e3o esteja 100% adaptado \u00e0\u00a0invas\u00e3o dos stories\u00a0nos seus apps preferidos, mas j\u00e1 \u00e9 hora de admitir, esta \u00e9 a realidade e n\u00e3o uma fase. O Facebook popularizou h\u00e1 10 anos o feed baseado em algor\u00edtimo. O Tinder popularizou o deslizar de sim\/n\u00e3o, junto ao consentimento bilateral nos aplicativos de encontro. O Blogger, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[471,505],"tags":[575,532,583,713,476,601,480,698,651],"global-tags":[],"class_list":["post-807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-blog","tag-facebook","tag-instagram","tag-mobile","tag-newsfeed","tag-redes-sociais","tag-snapchat","tag-social-media","tag-stories","tag-whatsapp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado - B-Young Social Media Co.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado\" \/>\n<meta property=\"og:description\" content=\"Talvez voc\u00ea ainda n\u00e3o esteja 100% adaptado \u00e0\u00a0invas\u00e3o dos stories\u00a0nos seus apps preferidos, mas j\u00e1 \u00e9 hora de admitir, esta \u00e9 a realidade e n\u00e3o uma fase. O Facebook popularizou h\u00e1 10 anos o feed baseado em algor\u00edtimo. O Tinder popularizou o deslizar de sim\/n\u00e3o, junto ao consentimento bilateral nos aplicativos de encontro. O Blogger, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/\" \/>\n<meta property=\"og:site_name\" content=\"B-Young Social Media Co.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agenciabyoung\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-11T21:32:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T14:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kaique C. Ribeiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaique C. Ribeiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/\"},\"author\":{\"name\":\"Kaique C. Ribeiro\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/person\\\/43d0dd6b09299911f71acce4257ac61d\"},\"headline\":\"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado\",\"datePublished\":\"2017-04-11T21:32:32+00:00\",\"dateModified\":\"2023-11-28T14:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/\"},\"wordCount\":756,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/snapchat-facebook-instagram.png\",\"keywords\":[\"Facebook\",\"instagram\",\"mobile\",\"newsfeed\",\"redes sociais\",\"snapchat\",\"social media\",\"stories\",\"whatsapp\"],\"articleSection\":[\"Artigos\",\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/\",\"name\":\"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado - B-Young Social Media Co.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/snapchat-facebook-instagram.png\",\"datePublished\":\"2017-04-11T21:32:32+00:00\",\"dateModified\":\"2023-11-28T14:38:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/snapchat-facebook-instagram.png\",\"contentUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/snapchat-facebook-instagram.png\",\"width\":1279,\"height\":727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/b-young.me\\\/en\\\/agency-of-social-media\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/\",\"name\":\"B-Young Social Media Co.\",\"description\":\"Ag\u00eancia de M\u00eddias Sociais\",\"publisher\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/b-young.me\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#organization\",\"name\":\"B-Young Social Media Co.\",\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_by.png\",\"contentUrl\":\"https:\\\/\\\/b-young.me\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_by.png\",\"width\":436,\"height\":131,\"caption\":\"B-Young Social Media Co.\"},\"image\":{\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agenciabyoung\",\"https:\\\/\\\/www.instagram.com\\\/agencia_byoung\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/b-young\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCzBkLbvLBatSTJrPjENDuww\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/b-young.me\\\/en\\\/#\\\/schema\\\/person\\\/43d0dd6b09299911f71acce4257ac61d\",\"name\":\"Kaique C. Ribeiro\",\"sameAs\":[\"https:\\\/\\\/karbro.com.br\"],\"url\":\"https:\\\/\\\/b-young.me\\\/en\\\/author\\\/kaique_dev\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado - B-Young Social Media Co.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/","og_locale":"en_US","og_type":"article","og_title":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado","og_description":"Talvez voc\u00ea ainda n\u00e3o esteja 100% adaptado \u00e0\u00a0invas\u00e3o dos stories\u00a0nos seus apps preferidos, mas j\u00e1 \u00e9 hora de admitir, esta \u00e9 a realidade e n\u00e3o uma fase. O Facebook popularizou h\u00e1 10 anos o feed baseado em algor\u00edtimo. O Tinder popularizou o deslizar de sim\/n\u00e3o, junto ao consentimento bilateral nos aplicativos de encontro. O Blogger, [&hellip;]","og_url":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/","og_site_name":"B-Young Social Media Co.","article_publisher":"https:\/\/www.facebook.com\/agenciabyoung","article_published_time":"2017-04-11T21:32:32+00:00","article_modified_time":"2023-11-28T14:38:29+00:00","og_image":[{"width":1279,"height":727,"url":"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png","type":"image\/png"}],"author":"Kaique C. Ribeiro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kaique C. Ribeiro","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#article","isPartOf":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/"},"author":{"name":"Kaique C. Ribeiro","@id":"https:\/\/b-young.me\/en\/#\/schema\/person\/43d0dd6b09299911f71acce4257ac61d"},"headline":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado","datePublished":"2017-04-11T21:32:32+00:00","dateModified":"2023-11-28T14:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/"},"wordCount":756,"commentCount":0,"publisher":{"@id":"https:\/\/b-young.me\/en\/#organization"},"image":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#primaryimage"},"thumbnailUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png","keywords":["Facebook","instagram","mobile","newsfeed","redes sociais","snapchat","social media","stories","whatsapp"],"articleSection":["Artigos","Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/","url":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/","name":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado - B-Young Social Media Co.","isPartOf":{"@id":"https:\/\/b-young.me\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#primaryimage"},"image":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#primaryimage"},"thumbnailUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png","datePublished":"2017-04-11T21:32:32+00:00","dateModified":"2023-11-28T14:38:29+00:00","breadcrumb":{"@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#primaryimage","url":"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png","contentUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2017\/04\/snapchat-facebook-instagram.png","width":1279,"height":727},{"@type":"BreadcrumbList","@id":"https:\/\/b-young.me\/en\/stories-e-o-novo-newsfeed-e-seu-smartphone-o-novo-teclado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/b-young.me\/en\/agency-of-social-media\/"},{"@type":"ListItem","position":2,"name":"Stories \u00e9 o novo newsfeed. E seu smartphone, o novo teclado"}]},{"@type":"WebSite","@id":"https:\/\/b-young.me\/en\/#website","url":"https:\/\/b-young.me\/en\/","name":"B-Young Social Media Co.","description":"Ag\u00eancia de M\u00eddias Sociais","publisher":{"@id":"https:\/\/b-young.me\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/b-young.me\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/b-young.me\/en\/#organization","name":"B-Young Social Media Co.","url":"https:\/\/b-young.me\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/b-young.me\/en\/#\/schema\/logo\/image\/","url":"https:\/\/b-young.me\/wp-content\/uploads\/2022\/02\/logo_by.png","contentUrl":"https:\/\/b-young.me\/wp-content\/uploads\/2022\/02\/logo_by.png","width":436,"height":131,"caption":"B-Young Social Media Co."},"image":{"@id":"https:\/\/b-young.me\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agenciabyoung","https:\/\/www.instagram.com\/agencia_byoung\/","https:\/\/www.linkedin.com\/company\/b-young\/","https:\/\/www.youtube.com\/channel\/UCzBkLbvLBatSTJrPjENDuww"]},{"@type":"Person","@id":"https:\/\/b-young.me\/en\/#\/schema\/person\/43d0dd6b09299911f71acce4257ac61d","name":"Kaique C. Ribeiro","sameAs":["https:\/\/karbro.com.br"],"url":"https:\/\/b-young.me\/en\/author\/kaique_dev\/"}]}},"_links":{"self":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts\/807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/comments?post=807"}],"version-history":[{"count":0,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/posts\/807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/media\/808"}],"wp:attachment":[{"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/media?parent=807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/categories?post=807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/tags?post=807"},{"taxonomy":"global-tags","embeddable":true,"href":"https:\/\/b-young.me\/en\/wp-json\/wp\/v2\/global-tags?post=807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}